{"id":2559,"date":"2026-08-21T18:26:44","date_gmt":"2026-08-21T16:26:44","guid":{"rendered":"https:\/\/jackmedia.be\/kairos\/?p=2559"},"modified":"2026-08-21T18:26:44","modified_gmt":"2026-08-21T16:26:44","slug":"dimanche-22-novembre-a-wierde-songs-from-silence","status":"publish","type":"post","link":"https:\/\/jackmedia.be\/kairos\/index.php\/2026\/08\/21\/dimanche-22-novembre-a-wierde-songs-from-silence\/","title":{"rendered":"Dimanche 22 novembre \u00e0 Wierde, Songs from silence"},"content":{"rendered":"<p>Le 22 novembre \u00e0 16H, nous chanterons notre programme \u00ab\u00a0Songs of silence, des compositrices de l&rsquo;ombre et de la lumi\u00e8re\u00a0\u00bb, dans la tr\u00e8s belle \u00e9glise de Wierde qui nous a d\u00e9j\u00e0 accueillis.<\/p>\n<p>R\u00e9servation:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 22 novembre \u00e0 16H, nous chanterons notre programme \u00ab\u00a0Songs of silence, des compositrices de l&rsquo;ombre et de la lumi\u00e8re\u00a0\u00bb, dans la tr\u00e8s belle \u00e9glise de Wierde qui nous a d\u00e9j\u00e0 accueillis. R\u00e9servation:<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/posts\/2559"}],"collection":[{"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/comments?post=2559"}],"version-history":[{"count":1,"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/posts\/2559\/revisions"}],"predecessor-version":[{"id":2560,"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/posts\/2559\/revisions\/2560"}],"wp:attachment":[{"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/media?parent=2559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/categories?post=2559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jackmedia.be\/kairos\/index.php\/wp-json\/wp\/v2\/tags?post=2559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}